{"id":6802,"date":"2025-09-24T14:12:49","date_gmt":"2025-09-24T12:12:49","guid":{"rendered":"https:\/\/ak-ski.ch\/?page_id=6802"},"modified":"2025-09-24T14:22:39","modified_gmt":"2025-09-24T12:22:39","slug":"bags","status":"publish","type":"page","link":"https:\/\/ak-ski.ch\/fr\/bags\/","title":{"rendered":"BAGS"},"content":{"rendered":"<div id=\"fws_6a049eaeaa26d\"  data-column-margin=\"custom\" data-midnight=\"light\"  class=\"wpb_row vc_row-fluid vc_row full-width-section  column-margin-4pct top_padding_phone_10px\"  style=\"padding-top: 200px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 light left\">\n\t<div style=\" color: #FFFFFF;\" class=\"vc_col-sm-4 wpb_column column_container vc_column_container col nectar-sticky-column-css has-animation no-extra-padding el_spacing_30px inherit_tablet inherit_phone\" data-cfc=\"true\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in\" data-delay=\"0\" >\n\t\t<div class=\"n-sticky\"><div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"nectar-responsive-text font_size_max_54px font_size_desktop_3vw font_size_tablet_5vw font_size_phone_34px font_line_height_1-1 nectar-link-underline-effect\"><h3>BAGS<\/h3>\n<\/div><div id=\"fws_6a049eaeaab62\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column no-extra-padding el_spacing_10px inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div><\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-8 wpb_column column_container vc_column_container col has-animation no-extra-padding el_spacing_20px inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-border-radius=\"20px\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"2000\" width=\"3556\" data-animation=\"none\" src=\"https:\/\/ak-ski.ch\/wp-content\/uploads\/2025\/09\/bags-titelbild.webp\" alt=\"\" srcset=\"https:\/\/ak-ski.ch\/wp-content\/uploads\/2025\/09\/bags-titelbild.webp 3556w, https:\/\/ak-ski.ch\/wp-content\/uploads\/2025\/09\/bags-titelbild-768x432.webp 768w, https:\/\/ak-ski.ch\/wp-content\/uploads\/2025\/09\/bags-titelbild-1536x864.webp 1536w, https:\/\/ak-ski.ch\/wp-content\/uploads\/2025\/09\/bags-titelbild-2048x1152.webp 2048w, https:\/\/ak-ski.ch\/wp-content\/uploads\/2025\/09\/bags-titelbild-600x337.webp 600w\" sizes=\"auto, (max-width: 3556px) 100vw, 3556px\" \/>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a049eaeabec3\"  data-column-margin=\"default\" data-midnight=\"light\" data-top-percent=\"10%\" data-bottom-percent=\"10%\"  class=\"wpb_row vc_row-fluid vc_row  zindex-set\"  style=\"padding-top: calc(100vw * 0.10); padding-bottom: calc(100vw * 0.10);  z-index: 3;\"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 light left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a049eaeac3af\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <a href=\"\/fr\/produit\/ak-ski-boot-bag\/\" target=\"_self\" class=\"\">\n              <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"1486\" width=\"2261\" data-animation=\"none\" src=\"https:\/\/ak-ski.ch\/wp-content\/uploads\/2025\/09\/bootbag-titelbild.webp\" alt=\"\" srcset=\"https:\/\/ak-ski.ch\/wp-content\/uploads\/2025\/09\/bootbag-titelbild.webp 2261w, https:\/\/ak-ski.ch\/wp-content\/uploads\/2025\/09\/bootbag-titelbild-768x505.webp 768w, https:\/\/ak-ski.ch\/wp-content\/uploads\/2025\/09\/bootbag-titelbild-1536x1010.webp 1536w, https:\/\/ak-ski.ch\/wp-content\/uploads\/2025\/09\/bootbag-titelbild-2048x1346.webp 2048w, https:\/\/ak-ski.ch\/wp-content\/uploads\/2025\/09\/bootbag-titelbild-600x394.webp 600w\" sizes=\"auto, (max-width: 2261px) 100vw, 2261px\" \/>\n            <\/a>\n          <\/div>\n        <\/div>\n      <\/div>\n      <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <a href=\"\/fr\/produit\/ak-ski-bag\/\" target=\"_self\" class=\"\">\n              <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"1486\" width=\"2261\" data-animation=\"none\" src=\"https:\/\/ak-ski.ch\/wp-content\/uploads\/2025\/09\/bootbag-titelbild_2.webp\" alt=\"\" srcset=\"https:\/\/ak-ski.ch\/wp-content\/uploads\/2025\/09\/bootbag-titelbild_2.webp 2261w, https:\/\/ak-ski.ch\/wp-content\/uploads\/2025\/09\/bootbag-titelbild_2-768x505.webp 768w, https:\/\/ak-ski.ch\/wp-content\/uploads\/2025\/09\/bootbag-titelbild_2-1536x1010.webp 1536w, https:\/\/ak-ski.ch\/wp-content\/uploads\/2025\/09\/bootbag-titelbild_2-2048x1346.webp 2048w, https:\/\/ak-ski.ch\/wp-content\/uploads\/2025\/09\/bootbag-titelbild_2-600x394.webp 600w\" sizes=\"auto, (max-width: 2261px) 100vw, 2261px\" \/>\n            <\/a>\n          <\/div>\n        <\/div>\n      <\/div>\n      <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"BAGS","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"ski":[27],"class_list":{"0":"post-6802","1":"page","2":"type-page","3":"status-publish","5":"ski-originals"},"_links":{"self":[{"href":"https:\/\/ak-ski.ch\/fr\/wp-json\/wp\/v2\/pages\/6802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ak-ski.ch\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ak-ski.ch\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ak-ski.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ak-ski.ch\/fr\/wp-json\/wp\/v2\/comments?post=6802"}],"version-history":[{"count":4,"href":"https:\/\/ak-ski.ch\/fr\/wp-json\/wp\/v2\/pages\/6802\/revisions"}],"predecessor-version":[{"id":6810,"href":"https:\/\/ak-ski.ch\/fr\/wp-json\/wp\/v2\/pages\/6802\/revisions\/6810"}],"wp:attachment":[{"href":"https:\/\/ak-ski.ch\/fr\/wp-json\/wp\/v2\/media?parent=6802"}],"wp:term":[{"taxonomy":"ski","embeddable":true,"href":"https:\/\/ak-ski.ch\/fr\/wp-json\/wp\/v2\/ski?post=6802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}