{"id":6937,"date":"2025-09-25T11:01:08","date_gmt":"2025-09-25T09:01:08","guid":{"rendered":"https:\/\/ak-ski.ch\/?page_id=6937"},"modified":"2025-09-25T11:09:31","modified_gmt":"2025-09-25T09:09:31","slug":"datenschutzerklaerung-2","status":"publish","type":"page","link":"https:\/\/ak-ski.ch\/fr\/datenschutzerklaerung-2\/","title":{"rendered":"D\u00e9claration de confidentialit\u00e9"},"content":{"rendered":"<div id=\"fws_6a04b02f2a689\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row  top_padding_phone_100px\"  style=\"padding-top: 200px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div style=\" color: #FFFFFF;\" class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\" data-cfc=\"true\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h2>D\u00e9claration de confidentialit\u00e9<\/h2>\n<p>Le service responsable au sens des lois sur la protection des donn\u00e9es, en particulier du r\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es (RGPD) de l'UE, est :<\/p>\n<p>AK Ski GmbH<br \/>Francesca Kuonen<br \/>Marco Kuonen<br \/>Unter Sagi 10<br \/>6362 Stansstad<\/p>\n<p>Courrier \u00e9lectronique : info@ak-ski.ch<br \/>Site web : https:\/\/ak-ski.ch\/<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"wp-block-heading\">Remarque g\u00e9n\u00e9rale<\/h3>\n<p>En vertu de l'article 13 de la Constitution f\u00e9d\u00e9rale suisse et des dispositions f\u00e9d\u00e9rales relatives \u00e0 la protection des donn\u00e9es (loi sur la protection des donn\u00e9es, LPD), toute personne a droit \u00e0 la protection de sa sph\u00e8re priv\u00e9e ainsi qu'\u00e0 la protection contre l'emploi abusif de ses donn\u00e9es personnelles. Les exploitants de ces pages prennent la protection de vos donn\u00e9es personnelles tr\u00e8s au s\u00e9rieux. Nous traitons vos donn\u00e9es personnelles de mani\u00e8re confidentielle et conform\u00e9ment aux dispositions l\u00e9gales en mati\u00e8re de protection des donn\u00e9es ainsi qu'\u00e0 la pr\u00e9sente d\u00e9claration de protection des donn\u00e9es.<\/p>\n<p>En collaboration avec nos fournisseurs d'h\u00e9bergement, nous nous effor\u00e7ons de prot\u00e9ger autant que possible les bases de donn\u00e9es contre les acc\u00e8s \u00e9trangers, les pertes, les abus ou les falsifications.<\/p>\n<p>Nous attirons votre attention sur le fait que la transmission de donn\u00e9es sur Internet (p. ex. lors de la communication par e-mail) peut pr\u00e9senter des failles de s\u00e9curit\u00e9. Une protection compl\u00e8te des donn\u00e9es contre l'acc\u00e8s par des tiers n'est pas possible.<\/p>\n<p>En utilisant ce site web, vous acceptez la collecte, le traitement et l'utilisation de donn\u00e9es conform\u00e9ment \u00e0 la description ci-dessous. Ce site web peut en principe \u00eatre visit\u00e9 sans enregistrement. Des donn\u00e9es telles que les pages appel\u00e9es ou le nom du fichier consult\u00e9, la date et l'heure sont enregistr\u00e9es sur le serveur \u00e0 des fins statistiques, sans que ces donn\u00e9es ne soient directement li\u00e9es \u00e0 votre personne. Les donn\u00e9es personnelles, en particulier le nom, l'adresse ou l'adresse e-mail, sont collect\u00e9es, dans la mesure du possible, sur une base volontaire. Sans votre consentement, ces donn\u00e9es ne sont pas transmises \u00e0 des tiers.<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"wp-block-heading\">Traitement des donn\u00e9es personnelles<\/h3>\n<p>Les donn\u00e9es personnelles sont toutes les donn\u00e9es qui se rapportent \u00e0 une personne identifi\u00e9e ou identifiable. Une personne concern\u00e9e est une personne au sujet de laquelle des donn\u00e9es personnelles sont trait\u00e9es. Le traitement comprend toute manipulation de donn\u00e9es personnelles, quels que soient les moyens et proc\u00e9d\u00e9s utilis\u00e9s, notamment la conservation, la communication, la collecte, l'effacement, la sauvegarde, la modification, la destruction et l'utilisation de donn\u00e9es personnelles.<\/p>\n<p>Nous traitons les donn\u00e9es personnelles en conformit\u00e9 avec le droit suisse de la protection des donn\u00e9es. Par ailleurs, nous traitons - dans la mesure o\u00f9 le RGPD de l'UE est applicable - les donn\u00e9es personnelles conform\u00e9ment aux bases juridiques suivantes en relation avec l'art. 6, al. 1 du RGPD :<\/p>\n<p>&nbsp;<\/p>\n<ul class=\"wp-block-list\">\n<li style=\"list-style-type: none;\">\n<ul class=\"wp-block-list\">\n<li>lit. a) Traitement de donn\u00e9es personnelles avec le consentement de la personne concern\u00e9e.<\/li>\n<li>let. b) traitement de donn\u00e9es personnelles en vue de l'ex\u00e9cution d'un contrat avec la personne concern\u00e9e ainsi que de l'ex\u00e9cution de mesures pr\u00e9contractuelles correspondantes.<\/li>\n<li>lit. c) Traitement de donn\u00e9es personnelles pour satisfaire \u00e0 une obligation l\u00e9gale \u00e0 laquelle nous sommes soumis conform\u00e9ment au droit \u00e9ventuellement applicable de l'UE ou conform\u00e9ment au droit \u00e9ventuellement applicable d'un pays dans lequel le RGPD est enti\u00e8rement ou partiellement applicable.<\/li>\n<li>let. d) traitement de donn\u00e9es personnelles pour prot\u00e9ger les int\u00e9r\u00eats vitaux de la personne concern\u00e9e ou d'une autre personne physique.<\/li>\n<li>let. f) traitement des donn\u00e9es personnelles afin de sauvegarder nos int\u00e9r\u00eats l\u00e9gitimes ou ceux de tiers, dans la mesure o\u00f9 les libert\u00e9s et les droits fondamentaux ainsi que les int\u00e9r\u00eats de la personne concern\u00e9e ne pr\u00e9valent pas. Les int\u00e9r\u00eats l\u00e9gitimes sont notamment notre int\u00e9r\u00eat commercial \u00e0 pouvoir mettre notre site web \u00e0 disposition, la s\u00e9curit\u00e9 de l'information, l'application de nos propres droits juridiques et le respect du droit suisse.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Nous traitons les donn\u00e9es personnelles pendant la dur\u00e9e n\u00e9cessaire \u00e0 l'objectif ou aux objectifs en question. En cas d'obligation de conservation plus longue en raison d'obligations l\u00e9gales ou autres auxquelles nous sommes soumis, nous limitons le traitement en cons\u00e9quence.<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"wp-block-heading\">D\u00e9claration de confidentialit\u00e9 pour les cookies<\/h3>\n<p>Ce site web utilise des cookies. Il s'agit de petits fichiers texte qui permettent d'enregistrer sur le terminal de l'utilisateur des informations sp\u00e9cifiques \u00e0 ce dernier lorsqu'il utilise le site web. Les cookies permettent notamment de d\u00e9terminer la fr\u00e9quence d'utilisation et le nombre d'utilisateurs des pages, d'analyser les comportements d'utilisation des pages, mais aussi de concevoir notre offre de mani\u00e8re plus conviviale. Les cookies restent enregistr\u00e9s apr\u00e8s la fin d'une session de navigation et peuvent \u00eatre consult\u00e9s lors d'une nouvelle visite du site. Si vous ne le souhaitez pas, vous devez configurer votre navigateur Internet de mani\u00e8re \u00e0 ce qu'il refuse les cookies.<\/p>\n<p>Il est possible de s'opposer de mani\u00e8re g\u00e9n\u00e9rale \u00e0 l'utilisation des cookies utilis\u00e9s \u00e0 des fins de marketing en ligne pour un grand nombre de services, en particulier dans le cas du tracking, via le site am\u00e9ricain\u00a0<a href=\"http:\/\/www.aboutads.info\/choices\/\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/www.aboutads.info\/choices\/<\/a>\u00a0ou le site de l'UE\u00a0<a href=\"http:\/\/www.youronlinechoices.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/www.youronlinechoices.com\/<\/a>\u00a0peuvent \u00eatre expliqu\u00e9s. En outre, il est possible d'emp\u00eacher l'enregistrement de cookies en les d\u00e9sactivant dans les param\u00e8tres du navigateur. Veuillez noter que dans ce cas, il se peut que vous ne puissiez pas utiliser toutes les fonctions de cette offre en ligne.<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"wp-block-heading\">D\u00e9claration de confidentialit\u00e9 pour le cryptage SSL\/TLS<\/h3>\n<p>Pour des raisons de s\u00e9curit\u00e9 et pour prot\u00e9ger la transmission de contenus confidentiels, comme par exemple les demandes que vous nous envoyez en tant qu'exploitant du site, ce site utilise un cryptage SSL\/TLS. Vous reconnaissez une connexion crypt\u00e9e au fait que la ligne d'adresse du navigateur passe de \"http:\/\/\" \u00e0 \"https:\/\/\" et au symbole du cadenas dans la ligne de votre navigateur.<\/p>\n<p>Si le cryptage SSL ou TLS est activ\u00e9, les donn\u00e9es que vous nous transmettez ne peuvent pas \u00eatre lues par des tiers.<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"wp-block-heading\">D\u00e9claration de protection des donn\u00e9es pour les fichiers journaux du serveur<\/h3>\n<p>Le fournisseur de ce site web collecte et enregistre automatiquement des informations dans ce que l'on appelle des fichiers journaux du serveur, que votre navigateur nous transmet automatiquement. Il s'agit de<\/p>\n<p>&nbsp;<\/p>\n<ul class=\"wp-block-list\">\n<li style=\"list-style-type: none;\">\n<ul class=\"wp-block-list\">\n<li>Type et version du navigateur<\/li>\n<li>le syst\u00e8me d'exploitation utilis\u00e9<\/li>\n<li>URL de r\u00e9f\u00e9rence<\/li>\n<li>nom d'h\u00f4te de l'ordinateur qui acc\u00e8de au site<\/li>\n<li>Heure de la demande du serveur<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Ces donn\u00e9es ne peuvent pas \u00eatre attribu\u00e9es \u00e0 des personnes pr\u00e9cises. Nous ne proc\u00e9dons pas \u00e0 un regroupement de ces donn\u00e9es avec d'autres sources de donn\u00e9es. Nous nous r\u00e9servons le droit de v\u00e9rifier ces donn\u00e9es ult\u00e9rieurement si nous avons connaissance d'indices concrets d'une utilisation ill\u00e9gale.<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"wp-block-heading\">Services de tiers<\/h3>\n<p>Ce site web utilise \u00e9ventuellement Google Maps pour l'int\u00e9gration de cartes, Google Invisible reCAPTCHA pour la protection contre les robots et les spams ainsi que YouTube pour l'int\u00e9gration de vid\u00e9os.<\/p>\n<p>Ces services de la soci\u00e9t\u00e9 am\u00e9ricaine Google LLC utilisent entre autres des cookies et, par cons\u00e9quent, des donn\u00e9es sont transmises \u00e0 Google aux \u00c9tats-Unis, mais nous partons du principe qu'aucun suivi personnel n'est effectu\u00e9 dans ce cadre du seul fait de l'utilisation de notre site Internet.<\/p>\n<p>Google s'est engag\u00e9 \u00e0 garantir une protection ad\u00e9quate des donn\u00e9es conform\u00e9ment au Privacy Shield am\u00e9ricano-europ\u00e9en et am\u00e9ricano-suisse.<\/p>\n<p>Pour plus d'informations, voir le\u00a0<a class=\"\" href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noreferrer noopener\">D\u00e9claration de confidentialit\u00e9 de Google<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"wp-block-heading\">D\u00e9claration de confidentialit\u00e9 pour le formulaire de contact<\/h3>\n<p>Si vous nous faites parvenir des demandes par le biais du formulaire de contact, les informations que vous avez fournies dans le formulaire de demande, y compris les donn\u00e9es de contact que vous y avez indiqu\u00e9es, sont enregistr\u00e9es chez nous \u00e0 des fins de traitement de la demande et en cas de questions de suivi. Nous ne transmettons pas ces donn\u00e9es sans votre consentement.<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"wp-block-heading\">Utilisation de Google Maps<\/h3>\n<p>Ce site web utilise l'offre de Google Maps. Cela nous permet d'afficher des cartes interactives directement sur le site web et vous permet d'utiliser confortablement la fonction de carte. Lors de votre visite sur le site web, Google re\u00e7oit l'information que vous avez consult\u00e9 la sous-page correspondante de notre site web. Cela se produit ind\u00e9pendamment du fait que Google mette \u00e0 disposition un compte d'utilisateur par lequel vous \u00eates connect\u00e9 ou qu'il n'existe pas de compte d'utilisateur. Si vous \u00eates connect\u00e9 \u00e0 Google, vos donn\u00e9es sont directement attribu\u00e9es \u00e0 votre compte. Si vous ne souhaitez pas l'attribution \u00e0 votre profil chez Google, vous devez vous d\u00e9connecter avant d'activer le bouton. Google enregistre vos donn\u00e9es en tant que profils d'utilisation et les utilise \u00e0 des fins de publicit\u00e9, d'\u00e9tude de march\u00e9 et\/ou de conception de son site Web en fonction des besoins. Une telle \u00e9valuation a lieu en particulier (m\u00eame pour les utilisateurs non connect\u00e9s) pour fournir une publicit\u00e9 adapt\u00e9e aux besoins et pour informer les autres utilisateurs du r\u00e9seau social de vos activit\u00e9s sur notre site web. Vous disposez d'un droit d'opposition \u00e0 la cr\u00e9ation de ces profils d'utilisateurs, que vous devez exercer en vous adressant \u00e0 Google. Pour plus d'informations sur l'objectif et l'\u00e9tendue de la collecte des donn\u00e9es et de leur traitement par Google, ainsi que pour conna\u00eetre vos droits en la mati\u00e8re et les possibilit\u00e9s de param\u00e9trage pour prot\u00e9ger votre vie priv\u00e9e, veuillez consulter le site :\u00a0<a href=\"http:\/\/www.google.de\/intl\/de\/policies\/privacy\" target=\"_blank\" rel=\"noreferrer noopener\">www.google.de\/intl\/de\/policies\/privacy<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"wp-block-heading\">Utilisation de Google reCAPTCHA<\/h3>\n<p>Ce site utilise le service reCAPTCHA de Google Inc (1600 Amphitheatre Parkway, Mountain View, CA 94043, \u00c9tats-Unis ; \"Google\"). La requ\u00eate a pour but de distinguer si la saisie est effectu\u00e9e par un \u00eatre humain ou par un traitement automatis\u00e9 par une machine. La requ\u00eate inclut l'envoi \u00e0 Google de l'adresse IP et, le cas \u00e9ch\u00e9ant, d'autres donn\u00e9es requises par Google pour le service reCAPTCHA. \u00c0 cette fin, votre saisie est transmise \u00e0 Google qui l'utilise. Votre adresse IP sera toutefois raccourcie au pr\u00e9alable par Google dans les \u00c9tats membres de l'Union europ\u00e9enne ou dans d'autres \u00c9tats signataires de l'accord sur l'Espace \u00e9conomique europ\u00e9en. Ce n'est que dans des cas exceptionnels que l'adresse IP compl\u00e8te est transmise \u00e0 un serveur de Google aux \u00c9tats-Unis et y est abr\u00e9g\u00e9e. Google utilisera ces informations pour le compte de l'exploitant de ce site web afin d'\u00e9valuer votre utilisation de ce service. L'adresse IP transmise par votre navigateur dans le cadre de reCaptcha ne sera pas recoup\u00e9e avec d'autres donn\u00e9es de Google. Vos donn\u00e9es sont alors \u00e9ventuellement transmises aux \u00c9tats-Unis. Pour les transferts de donn\u00e9es vers les \u00c9tats-Unis, il existe une d\u00e9cision d'ad\u00e9quation de la Commission europ\u00e9enne, le \"Privacy Shield\". Google participe au \"Privacy Shield\" et s'est soumis aux directives. En cliquant sur la demande, vous consentez au traitement de vos donn\u00e9es. Le traitement est effectu\u00e9 sur la base de l'art. 6 (1) lettre a du RGPD avec votre consentement. Vous pouvez r\u00e9voquer votre consentement \u00e0 tout moment, sans que la l\u00e9gitimit\u00e9 du traitement effectu\u00e9 sur la base du consentement jusqu'\u00e0 la r\u00e9vocation n'en soit affect\u00e9e.<\/p>\n<p>Vous trouverez de plus amples informations sur Google reCAPTCHA ainsi que sur la d\u00e9claration de confidentialit\u00e9 correspondante \u00e0 l'adresse suivante :\u00a0<a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/policies.google.com\/privacy?hl=de<\/a><\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"wp-block-heading\">D\u00e9claration de confidentialit\u00e9 pour Google Analytics<\/h3>\n<p>Ce site web utilise Google Analytics, un service d'analyse web de Google Ireland Limited. Si le responsable du traitement des donn\u00e9es sur ce site web est situ\u00e9 en dehors de l'Espace \u00e9conomique europ\u00e9en ou de la Suisse, le traitement des donn\u00e9es Google Analytics est effectu\u00e9 par Google LLC. Google LLC et Google Ireland Limited sont ci-apr\u00e8s d\u00e9nomm\u00e9s \"Google\".<\/p>\n<p>Les statistiques obtenues nous permettent d'am\u00e9liorer notre offre et de la rendre plus int\u00e9ressante pour vous en tant qu'utilisateur. Ce site utilise \u00e9galement Google Analytics pour une analyse des flux de visiteurs sur tous les appareils, qui est effectu\u00e9e \u00e0 l'aide d'un ID utilisateur. Si vous disposez d'un compte d'utilisateur Google, vous pouvez d\u00e9sactiver l'analyse de votre utilisation sur plusieurs appareils dans les param\u00e8tres de ce compte, sous \"Mes donn\u00e9es\", \"Donn\u00e9es personnelles\".<\/p>\n<p>La base juridique de l'utilisation de Google Analytics est l'article 6, paragraphe 1, phrase 1, point f du RGPD. L'adresse IP transmise par votre navigateur dans le cadre de Google Analytics n'est pas recoup\u00e9e avec d'autres donn\u00e9es de Google. Nous attirons votre attention sur le fait que sur ce site Internet, Google Analytics a \u00e9t\u00e9 compl\u00e9t\u00e9 par le code \"_anonymizeIp() ;\" afin de garantir une saisie anonyme des adresses IP. Les adresses IP sont ainsi trait\u00e9es sous forme abr\u00e9g\u00e9e, ce qui permet d'exclure tout lien avec des personnes. Dans la mesure o\u00f9 les donn\u00e9es collect\u00e9es vous concernant pr\u00e9sentent un lien avec une personne, celui-ci est imm\u00e9diatement exclu et les donn\u00e9es personnelles sont ainsi imm\u00e9diatement supprim\u00e9es.<\/p>\n<p>Ce n'est que dans des cas exceptionnels que l'adresse IP compl\u00e8te est transmise \u00e0 un serveur de Google aux \u00c9tats-Unis et y est raccourcie. Google utilisera ces informations pour le compte de l'exploitant de ce site web afin d'\u00e9valuer votre utilisation du site web, de compiler des rapports sur les activit\u00e9s du site web et de fournir \u00e0 l'exploitant du site web d'autres services li\u00e9s \u00e0 l'utilisation du site web et d'Internet. Dans les cas exceptionnels o\u00f9 des donn\u00e9es personnelles sont transf\u00e9r\u00e9es aux \u00c9tats-Unis, Google s'est soumis au Privacy Shield UE-US,\u00a0<a href=\"https:\/\/www.privacyshield.gov\/EU-US-Framework\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.privacyshield.gov\/EU-US-Framework<\/a>.<\/p>\n<p>Google Analytics utilise des cookies. Les informations g\u00e9n\u00e9r\u00e9es par le cookie concernant votre utilisation de ce site web sont g\u00e9n\u00e9ralement transmises \u00e0 un serveur de Google aux \u00c9tats-Unis et y sont enregistr\u00e9es. Vous pouvez emp\u00eacher l'enregistrement des cookies en param\u00e9trant votre logiciel de navigation en cons\u00e9quence ; nous attirons toutefois votre attention sur le fait que, dans ce cas, vous ne pourrez peut-\u00eatre pas utiliser toutes les fonctions de ce site web dans leur int\u00e9gralit\u00e9. Vous pouvez en outre emp\u00eacher la saisie par Google des donn\u00e9es g\u00e9n\u00e9r\u00e9es par le cookie et se rapportant \u00e0 votre utilisation du site web (y compris votre adresse IP) ainsi que le traitement de ces donn\u00e9es par Google en t\u00e9l\u00e9chargeant et en installant le plug-in de navigateur disponible sous le lien suivant :\u00a0<a href=\"https:\/\/www.swissanwalt.ch\/de\/gaoptout.aspx\" target=\"_blank\" rel=\"noreferrer noopener\">D\u00e9sactiver Google Analytics<\/a>.<\/p>\n<p>En outre, vous pouvez \u00e9galement emp\u00eacher l'utilisation de Google Analytics en cliquant sur ce lien :\u00a0<a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de\" target=\"_blank\" rel=\"noreferrer noopener\">D\u00e9sactiver Google Analytics<\/a>. Un cookie opt-out est alors enregistr\u00e9 sur votre support de donn\u00e9es, ce qui emp\u00eache le traitement de vos donn\u00e9es personnelles par Google Analytics. Veuillez noter que si vous supprimez tous les cookies de votre terminal, ces cookies opt-out seront \u00e9galement supprim\u00e9s, c'est-\u00e0-dire que vous devrez \u00e0 nouveau placer les cookies opt-out si vous souhaitez continuer \u00e0 emp\u00eacher cette forme de collecte de donn\u00e9es. Les cookies opt-out sont plac\u00e9s par navigateur et par ordinateur\/terminal et doivent donc \u00eatre activ\u00e9s s\u00e9par\u00e9ment pour chaque navigateur, ordinateur ou autre terminal.<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"wp-block-heading\">D\u00e9claration de confidentialit\u00e9 pour l'utilisation de Google Web Fonts<\/h3>\n<p>Ce site web utilise des polices web mises \u00e0 disposition par Google pour l'affichage uniforme des polices de caract\u00e8res. Lorsque vous consultez une page, votre navigateur charge les polices web n\u00e9cessaires dans le cache de votre navigateur afin d'afficher correctement les textes et les polices. Si votre navigateur ne prend pas en charge les polices web, une police standard est utilis\u00e9e par votre ordinateur.<\/p>\n<p>Pour plus d'informations sur Google Web Fonts, voir\u00a0<a href=\"https:\/\/developers.google.com\/fonts\/faq\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/developers.google.com\/fonts\/faq<\/a>\u00a0et dans la d\u00e9claration de confidentialit\u00e9 de Google :\u00a0<a href=\"https:\/\/www.google.com\/policies\/privacy\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.google.com\/policies\/privacy\/<\/a><\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"wp-block-heading\">D\u00e9claration de confidentialit\u00e9 pour Facebook<\/h3>\n<p>Ce site utilise des fonctions de Facebook Inc, 1601 S. California Ave, Palo Alto, CA 94304, USA . Lorsque vous consultez nos pages avec des plug-ins Facebook, une connexion est \u00e9tablie entre votre navigateur et les serveurs de Facebook. Des donn\u00e9es sont alors transmises \u00e0 Facebook. Si vous poss\u00e9dez un compte Facebook, ces donn\u00e9es peuvent y \u00eatre associ\u00e9es. Si vous ne souhaitez pas que ces donn\u00e9es soient associ\u00e9es \u00e0 votre compte Facebook, veuillez vous d\u00e9connecter de Facebook avant de visiter notre site. Les interactions, en particulier l'utilisation d'une fonction de commentaire ou le clic sur un bouton \"Like\" ou \"Partager\", sont \u00e9galement transmises \u00e0 Facebook. Pour en savoir plus, voir\u00a0<a href=\"https:\/\/de-de.facebook.com\/about\/privacy\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/de-de.facebook.com\/about\/privacy<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"wp-block-heading\">D\u00e9claration de confidentialit\u00e9 pour Instagram<\/h3>\n<p>Des fonctions du service Instagram sont int\u00e9gr\u00e9es sur notre site web. Ces fonctions sont propos\u00e9es par Instagram Inc., 1601 Willow Road, Menlo Park, CA, 94025, USA. Si vous \u00eates connect\u00e9 \u00e0 votre compte Instagram, vous pouvez, en cliquant sur le bouton Instagram, relier le contenu de nos pages \u00e0 votre profil Instagram. Instagram peut ainsi associer la visite de nos pages \u00e0 votre compte d'utilisateur. Nous attirons votre attention sur le fait qu'en tant que fournisseur des pages, nous n'avons pas connaissance du contenu des donn\u00e9es transmises ni de leur utilisation par Instagram.<\/p>\n<p>Pour plus d'informations \u00e0 ce sujet, veuillez consulter la d\u00e9claration de confidentialit\u00e9 d'Instagram :\u00a0<a href=\"https:\/\/instagram.com\/about\/legal\/privacy\/\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/instagram.com\/about\/legal\/privacy\/<\/a><\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"wp-block-heading\">Prestataires de services de paiement externes<\/h3>\n<p>Ce site web fait appel \u00e0 des prestataires de services de paiement externes, dont les plateformes permettent aux utilisateurs et \u00e0 nous-m\u00eames d'effectuer des transactions de paiement. Par exemple, via<\/p>\n<p>&nbsp;<\/p>\n<ul class=\"wp-block-list\">\n<li style=\"list-style-type: none;\">\n<ul class=\"wp-block-list\">\n<li>PostFinance (https:\/\/www.postfinance.ch\/de\/detail\/rechtliches-barrierefreiheit.html)<\/li>\n<li>Visa (https:\/\/www.visa.de\/nutzungsbedingungen\/visa-privacy-center.html)<\/li>\n<li>Mastercard (https:\/\/www.mastercard.ch\/de-ch\/datenschutz.html)<\/li>\n<li>American Express (https:\/\/www.americanexpress.com\/de\/content\/privacy-policy-statement.html)<\/li>\n<li>Paypal (https:\/\/www.paypal.com\/de\/webapps\/mpp\/ua\/privacy-full)<\/li>\n<li>Bexio AG (https:\/\/www.bexio.com\/de-CH\/datenschutz)<\/li>\n<li>Payrexx AG (https:\/\/www.payrexx.ch\/site\/assets\/files\/2592\/datenschutzerklaerung.pdf)<\/li>\n<li>Apple Pay (https:\/\/support.apple.com\/de-ch\/ht203027)<\/li>\n<li>Stripe (https:\/\/stripe.com\/ch\/privacy)<\/li>\n<li>Klarna (https:\/\/www.klarna.com\/de\/datenschutz\/)<\/li>\n<li>Skrill (https:\/\/www.skrill.com\/de\/fusszeile\/datenschutzrichtlinie\/)<\/li>\n<li>Giropay (https:\/\/www.giropay.de\/rechtliches\/datenschutz-agb\/) etc.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Dans le cadre de l'ex\u00e9cution des contrats, nous faisons appel aux prestataires de services de paiement sur la base de l'ordonnance suisse sur la protection des donn\u00e9es ainsi que, si n\u00e9cessaire, de l'art. 6, al. 1, let. b. EU-DSGVO. Par ailleurs, nous faisons appel \u00e0 des prestataires de services de paiement externes sur la base de nos int\u00e9r\u00eats l\u00e9gitimes conform\u00e9ment \u00e0 l'ordonnance suisse sur la protection des donn\u00e9es ainsi que, si n\u00e9cessaire, \u00e0 l'art. 6, al. 1, let. f. EU-DSGVO, afin d'offrir \u00e0 nos utilisateurs des possibilit\u00e9s de paiement efficaces et s\u00fbres.<\/p>\n<p>Les donn\u00e9es trait\u00e9es par les prestataires de services de paiement comprennent les donn\u00e9es d'inventaire, telles que le nom et l'adresse, les donn\u00e9es bancaires, telles que, entre autres, les num\u00e9ros de compte ou de carte de cr\u00e9dit, les mots de passe, les num\u00e9ros TAN et les sommes de contr\u00f4le, ainsi que les donn\u00e9es relatives au contrat, aux totaux et au b\u00e9n\u00e9ficiaire. Ces informations sont n\u00e9cessaires pour effectuer les transactions. Les donn\u00e9es saisies ne sont toutefois trait\u00e9es que par les prestataires de services de paiement et stock\u00e9es chez eux. En tant qu'op\u00e9rateur, nous ne recevons aucune information sur le compte (bancaire) ou la carte de cr\u00e9dit, mais uniquement des informations permettant de confirmer (accepter) ou de refuser le paiement. Dans certaines circonstances, les donn\u00e9es sont transmises par les prestataires de services de paiement \u00e0 des agences d'\u00e9valuation du cr\u00e9dit. Cette transmission a pour but de v\u00e9rifier l'identit\u00e9 et la solvabilit\u00e9. Nous renvoyons \u00e0 ce sujet aux conditions g\u00e9n\u00e9rales et aux informations sur la protection des donn\u00e9es des prestataires de services de paiement.<\/p>\n<p>Les op\u00e9rations de paiement sont soumises aux conditions g\u00e9n\u00e9rales et aux informations relatives \u00e0 la protection des donn\u00e9es des prestataires de services de paiement respectifs, qui peuvent \u00eatre consult\u00e9es sur le site Internet ou l'application de transaction correspondants. Nous y renvoyons \u00e9galement pour de plus amples informations et pour faire valoir les droits de r\u00e9vocation, d'information et autres droits des personnes concern\u00e9es.<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"wp-block-heading\">D\u00e9claration de confidentialit\u00e9 pour YouTube<\/h3>\n<p>Des fonctions du service \"YouTube\" sont int\u00e9gr\u00e9es \u00e0 ce site web. \"YouTube\" appartient \u00e0 Google Ireland Limited, une soci\u00e9t\u00e9 enregistr\u00e9e et exploit\u00e9e selon le droit irlandais, dont le si\u00e8ge est situ\u00e9 \u00e0 Gordon House, Barrow Street, Dublin 4, Irlande, et qui exploite les services dans l'Espace \u00e9conomique europ\u00e9en et en Suisse.<\/p>\n<p>Votre accord juridique avec YouTube est constitu\u00e9 des termes et conditions indiqu\u00e9s dans le lien suivant :\u00a0<a href=\"https:\/\/www.youtube.com\/static?gl=DE&amp;template=terms&amp;hl=de\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.youtube.com\/static?gl=de&amp;template=terms&amp;hl=de<\/a>. Les pr\u00e9sentes dispositions constituent un accord juridiquement contraignant entre vous et YouTube concernant l'utilisation des services. Les r\u00e8gles de confidentialit\u00e9 de Google expliquent comment \"YouTube\" traite et prot\u00e8ge vos donn\u00e9es personnelles lorsque vous utilisez le service.<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"wp-block-heading\">D\u00e9claration de confidentialit\u00e9 pour Vimeo<\/h3>\n<p>Sur ce site web, des plugins du portail vid\u00e9o Vimeo de Vimeo, LLC, 555 West 18th Street, New York, New York 10011, USA sont int\u00e9gr\u00e9s. Chaque fois que vous consultez une page qui propose un ou plusieurs clips vid\u00e9o Vimeo, une connexion directe est \u00e9tablie entre votre navigateur et un serveur de Vimeo aux \u00c9tats-Unis. Les informations relatives \u00e0 votre visite et votre adresse IP y sont enregistr\u00e9es. En interagissant avec les plugins Vimeo (par exemple en cliquant sur le bouton de d\u00e9marrage), ces informations sont \u00e9galement transmises \u00e0 Vimeo et y sont enregistr\u00e9es. Vous trouverez la d\u00e9claration de protection des donn\u00e9es pour Vimeo avec des informations plus d\u00e9taill\u00e9es sur la collecte et l'utilisation de vos donn\u00e9es par Vimeo dans le\u00a0<a href=\"http:\/\/vimeo.com\/privacy\">D\u00e9claration de confidentialit\u00e9 de Vimeo<\/a>.<\/p>\n<p>Si vous avez un compte utilisateur Vimeo et que vous ne souhaitez pas que Vimeo collecte des donn\u00e9es vous concernant par le biais de ce site web et les associe \u00e0 vos donn\u00e9es de membre stock\u00e9es chez Vimeo, vous devez vous d\u00e9connecter de Vimeo avant de visiter ce site web.<\/p>\n<p>En outre, Vimeo fait appel au tracker Google Analytics via un iFrame dans lequel la vid\u00e9o est appel\u00e9e. Il s'agit d'un tracking propre \u00e0 Vimeo, auquel nous n'avons pas acc\u00e8s. Vous pouvez emp\u00eacher le tracking par Google Analytics en utilisant les outils de d\u00e9sactivation que Google propose pour certains navigateurs Internet. Vous pouvez en outre emp\u00eacher la saisie par Google des donn\u00e9es g\u00e9n\u00e9r\u00e9es par Google Analytics et se rapportant \u00e0 votre utilisation du site web (y compris votre adresse IP) ainsi que le traitement de ces donn\u00e9es par Google en t\u00e9l\u00e9chargeant et en installant le plug-in de navigateur disponible sous le lien suivant :<\/p>\n<p>&nbsp;<\/p>\n<figure class=\"wp-block-embed\">\n<div class=\"wp-block-embed__wrapper\">https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de<\/div>\n<\/figure>\n<p>&nbsp;<\/p>\n<h3 class=\"wp-block-heading\">Clause de non-responsabilit\u00e9 g\u00e9n\u00e9rale<\/h3>\n<p>Toutes les informations de notre offre Internet ont \u00e9t\u00e9 soigneusement v\u00e9rifi\u00e9es. Nous nous effor\u00e7ons de proposer des informations actuelles, correctes et compl\u00e8tes. N\u00e9anmoins, l'apparition d'erreurs ne peut pas \u00eatre totalement exclue, ce qui nous emp\u00eache de garantir l'exhaustivit\u00e9, l'exactitude et l'actualit\u00e9 des informations, m\u00eame de nature journalistique et r\u00e9dactionnelle. Nous d\u00e9clinons toute responsabilit\u00e9 pour les dommages mat\u00e9riels ou immat\u00e9riels caus\u00e9s par l'utilisation des informations propos\u00e9es, dans la mesure o\u00f9 il n'est pas prouv\u00e9 qu'il s'agit d'une faute intentionnelle ou d'une n\u00e9gligence grave.<\/p>\n<p>L'\u00e9diteur peut, \u00e0 sa seule discr\u00e9tion et sans pr\u00e9avis, modifier ou supprimer des textes et n'est pas tenu de mettre \u00e0 jour le contenu de ce site. L'utilisation ou l'acc\u00e8s \u00e0 ce site web se fait aux risques et p\u00e9rils du visiteur. L'\u00e9diteur, ses mandants ou ses partenaires ne sont pas responsables des dommages, tels que les dommages directs, indirects, accidentels, \u00e0 d\u00e9terminer concr\u00e8tement \u00e0 l'avance ou cons\u00e9cutifs, pr\u00e9tendument caus\u00e9s par la visite de ce site web et n'assument par cons\u00e9quent aucune responsabilit\u00e9 \u00e0 cet \u00e9gard.<\/p>\n<p>L'\u00e9diteur d\u00e9cline \u00e9galement toute responsabilit\u00e9 quant au contenu et \u00e0 la disponibilit\u00e9 des sites web de tiers accessibles via des liens externes de ce site. Seuls les exploitants de ces sites sont responsables de leur contenu. L'\u00e9diteur se distancie ainsi express\u00e9ment de tous les contenus de tiers qui pourraient \u00e9ventuellement relever du droit p\u00e9nal ou de la responsabilit\u00e9 civile ou qui pourraient \u00eatre contraires aux bonnes m\u0153urs.<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"wp-block-heading\">Modifications<\/h3>\n<p>Nous pouvons adapter cette d\u00e9claration de protection des donn\u00e9es \u00e0 tout moment et sans pr\u00e9avis. La version actuelle publi\u00e9e sur notre site web fait foi. Si la d\u00e9claration de protection des donn\u00e9es fait partie d'un accord avec vous, nous vous informerons de la modification par e-mail ou par tout autre moyen appropri\u00e9 en cas de mise \u00e0 jour.<\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"wp-block-heading\">Questions au d\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es<\/h3>\n<p>Si vous avez des questions concernant la protection des donn\u00e9es, veuillez nous envoyer un e-mail ou vous adresser directement \u00e0 la personne responsable de la protection des donn\u00e9es au sein de notre organisation, dont la liste figure au d\u00e9but de la pr\u00e9sente d\u00e9claration de confidentialit\u00e9.<\/p>\n<p>Stansstad, 02.10.2020<br \/>Source :\u00a0<a href=\"https:\/\/www.swissanwalt.ch\/\" target=\"_blank\" rel=\"noreferrer noopener\">SwissAnwalt<\/a><\/p>\n<p>&nbsp;<\/p>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"Datenschutzerkl\u00e4rung Verantwortliche Stelle im Sinne der Datenschutzgesetze, insbesondere der EU-Datenschutzgrundverordnung (DSGVO), ist: AK Ski GmbHFrancesca KuonenMarco KuonenUnter Sagi 106362 Stansstad E-Mail: info@ak-ski.chWebSite: https:\/\/ak-ski.ch\/ &nbsp; Allgemeiner Hinweis Gest\u00fctzt auf Artikel 13...","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"ski":[],"class_list":["post-6937","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/ak-ski.ch\/fr\/wp-json\/wp\/v2\/pages\/6937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ak-ski.ch\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ak-ski.ch\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ak-ski.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ak-ski.ch\/fr\/wp-json\/wp\/v2\/comments?post=6937"}],"version-history":[{"count":2,"href":"https:\/\/ak-ski.ch\/fr\/wp-json\/wp\/v2\/pages\/6937\/revisions"}],"predecessor-version":[{"id":6944,"href":"https:\/\/ak-ski.ch\/fr\/wp-json\/wp\/v2\/pages\/6937\/revisions\/6944"}],"wp:attachment":[{"href":"https:\/\/ak-ski.ch\/fr\/wp-json\/wp\/v2\/media?parent=6937"}],"wp:term":[{"taxonomy":"ski","embeddable":true,"href":"https:\/\/ak-ski.ch\/fr\/wp-json\/wp\/v2\/ski?post=6937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}